{"id":21141,"date":"2015-11-23T09:26:48","date_gmt":"2015-11-23T08:26:48","guid":{"rendered":"https:\/\/saltaconmigo.com\/blog\/?p=21141"},"modified":"2021-11-10T10:58:34","modified_gmt":"2021-11-10T09:58:34","slug":"las-historias-de-la-abadia-de-kylemore","status":"publish","type":"post","link":"https:\/\/saltaconmigo.com\/blog\/2015\/11\/las-historias-de-la-abadia-de-kylemore\/","title":{"rendered":"Las historias de la abad\u00eda de Kylemore"},"content":{"rendered":"<p>La <strong><a href=\"https:\/\/saltaconmigo.com\/blog\/2015\/10\/ruta-en-coche-connemara-irlanda\/\">\u201cbelleza salvaje\u201d de Connemara<\/a><\/strong> ya nos hab\u00eda conquistado cuando llegamos a <strong>Kylemore<\/strong> esperando encontrarnos con una <strong>abad\u00eda<\/strong>. Connemara segu\u00eda sorprendi\u00e9ndonos. S\u00ed, sus carreteras sinuosas segu\u00edan llev\u00e1ndonos a lo inesperado. Porque la <strong>Kylemore Abbey<\/strong> no es s\u00f3lo una abad\u00eda, ni un castillo, ni un parque, ni una iglesia, ni un mausoleo. Es algo m\u00e1s, uno de esos lugares a los que llegas sin conocerlos y de los que te vas con la sensaci\u00f3n de no haberlos conocidos tan bien como te hubiera gustado. Un conocido que te habr\u00eda encantado se convirtiera un amigo.<\/p>\n<p><strong>Un lugar con historia<\/strong>, no muy larga para los est\u00e1ndares europeos \u2013unos 150 a\u00f1os\u2013 pero s\u00ed muy intensa. <strong>Un lugar con historias<\/strong>. Historias de <strong>enamorados, nobles, reyes y campesinos<\/strong> dignas de un cuento de Disney. Historias de <strong>amor, de pasi\u00f3n, de riqueza, de alegr\u00eda, de guerras, de pobreza, de muerte y de esperanza<\/strong>. Donde te gustar\u00eda que los \u00e1rboles, las piedras y hasta el parqu\u00e9 de roble te hablaran en lugar que dejarse simplemente admirar. Y un lugar en el que tampoco te sorprender\u00edas tanto si pasara\u2026 porque Connemara tiene un poco de magia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21145 size-full\" title=\"La abad\u00eda de Kylemore, un lugar de cuento de hadas y de saltos\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Exterior-Salto.jpg\" alt=\"Irlanda Abadia Kylemore Exterior Salto\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Exterior-Salto.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Exterior-Salto-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Exterior-Salto-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>No os contar\u00e9 toda la historia, ni las historias, de la <strong>abad\u00eda de Kylemore<\/strong>, pero s\u00ed algunas de ellas junto con unas pocas <strong>curiosidades<\/strong>, para invitaros a haceros conocidos\u2026 o amigos.<\/p>\n<h2>El nacimiento de cuento del castillo de Kylemore en el oeste de Irlanda<\/h2>\n<p>\u00c9rase una vez, una feliz pareja de Manchester que, en su luna de miel, se fue de viaje a Irlanda. As\u00ed, como en un cuento, empieza la<strong> historia de Kylemore<\/strong>. Cuando <strong>Mitchell y Margaret Henry<\/strong> llegaron a este terreno salvaje que en la \u00e9poca, en <strong>1850<\/strong>, era un coto de caza con s\u00f3lo una peque\u00f1a construcci\u00f3n: el <strong>Kylemore Lodge<\/strong>. Margaret qued\u00f3 tan prendada de Connemara que su marido, al recibir la herencia de su padre, dej\u00f3 su carrera de cirujano y compr\u00f3 las 6.000 hect\u00e1reas del terreno de Kylemore, con su lago, sus bosques, su maleza, sus turberas y sus zonas pantanosas. Como regalo y homenaje a su esposa, el doctor Henry, entre 1867 y 1871, sane\u00f3 los terrenos y <strong>construy\u00f3 un castillo<\/strong>.<\/p>\n<p>La construcci\u00f3n de Kylemore en una zona de terrenos salvajes fue una obra impresionante en la que se utilizaron las \u00faltimas tecnolog\u00edas de la \u00e9poca y no se repar\u00f3 en gastos: en su <strong>jard\u00edn victoriano amurallado<\/strong>, el <strong>m\u00e1s grande de Irlanda<\/strong>, hab\u00eda 21 invernaderos calentados por tuber\u00edas de agua; en 1893 el castillo ya generaba su propia hidroelectricidad utilizando el agua del lago Touther; Kylemore lleg\u00f3 a tener su propia brigada de bomberos y para su construcci\u00f3n se reorient\u00f3 la carretera p\u00fablica hacia Clifden y la parte original que pasaba por la propiedad del castillo fue convertida en una avenida privada.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21143 size-full\" title=\"El lago seguro que vio muchos paseos de los enamorados Henry por al abad\u00eda de Kylemore\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Banco-Lago.jpg\" alt=\"Irlanda Abadia Kylemore Banco Lago\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Banco-Lago.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Banco-Lago-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Banco-Lago-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Mitchell y Margaret Henry se conoc\u00edan por su generosidad: ten\u00edan unos 300 trabajadores viviendo en su terreno a los que pagaban mucho m\u00e1s que la media por su trabajo en la finca; fundaron una escuela para sus hijos; redujeron las rentas en los tiempos m\u00e1s duros; mejoraron las condiciones de sus <em>\u201ccottages\u201d<\/em>, etc.<\/p>\n<h2>El final infeliz del cuento de hadas del castillo de Kylemore<\/h2>\n<p>Los Mitchell llegaron a tener nueve hijos y vivieron felices y comieron perdices en Kylemore junto con sus trabajadores hasta que\u2026 en 1874 Margaret, de vuelta de un viaje a Egipto, cay\u00f3 enferma de disenter\u00eda y muri\u00f3.<\/p>\n<p>Entre 1877 y 1881 Mitchell construy\u00f3 en su honor una \u201c<strong>catedral en miniatura<\/strong>\u201d: una <strong>peque\u00f1a iglesia neog\u00f3tica<\/strong> donde las g\u00e1rgolas y animales tenebrosos se sustitu\u00edan por \u00e1ngeles sonrientes, flores y p\u00e1jaros.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21147 size-full\" title=\"La peque\u00f1a iglesia de la abad\u00eda de Kylemore\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Iglesia.jpg\" alt=\"Irlanda Abadia Kylemore Iglesia\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Iglesia.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Iglesia-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Iglesia-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>A la muerte de Mitchell, en 1910, sus cenizas fueron llevadas a Kylemore y echadas junto a los restos de su difunta esposa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21153 size-full\" title=\"El mausoleo de los Henry en la abad\u00eda de Kylemore\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Mausoleo-Henry.jpg\" alt=\"Irlanda Abadia Kylemore Mausoleo Henry\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Mausoleo-Henry.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Mausoleo-Henry-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Mausoleo-Henry-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>Kylemore: castillo de duques y de reyes<\/h2>\n<p>Antes de su muerte, en 1903, Mitchell Henry hab\u00eda vendido el castillo a sus amigos los <strong>duques de Manchester<\/strong>.<\/p>\n<p>Ese a\u00f1o el castillo hab\u00eda sido visitado por el mism\u00edsimo <strong>rey de Inglaterra Eduardo VII<\/strong>, junto con la reina y la princesa Victoria. Seg\u00fan los rumores de la \u00e9poca, <strong>el monarca quiso comprar el castillo<\/strong> pero dijo que era <strong>demasiado caro incluso para un rey<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21155 size-full\" title=\"La abad\u00eda de Kylemore se asoma al lago, en un paisaje de cuento\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Vista.jpg\" alt=\"Irlanda Abadia Kylemore Vista\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Vista.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Vista-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Vista-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Lo cierto es que el duque de Manchester, adicto al juego, se arruin\u00f3 despu\u00e9s de la compra y el castillo pas\u00f3 a manos de un especulador de Londres. Desde la muerte de Margaret el castillo parec\u00eda maldecido\u2026.<\/p>\n<h2>De castillo a una de las abad\u00edas m\u00e1s conocidas de Irlanda: La abad\u00eda de Kylemore<\/h2>\n<p>El castillo de Kylemore se convirti\u00f3 en <strong>abad\u00eda<\/strong> cuando una c<strong>omunidad de monjas belgas de la orden benedictina<\/strong> lleg\u00f3 aqu\u00ed en 1920 y lo compr\u00f3, despu\u00e9s de que su abad\u00eda de <strong>Ypres, en Flandes<\/strong>, fuese bombardeada por los alemanes durante la primera guerra mundial.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20428 size-full\" title=\"La abad\u00eda de Kylemore, uno de los imprescindibles de Connemara\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/10\/Irlanda-Connemara-Abadia-ylemore.jpg\" alt=\"Irlanda Connemara Abadia ylemore\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/10\/Irlanda-Connemara-Abadia-ylemore.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/10\/Irlanda-Connemara-Abadia-ylemore-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/10\/Irlanda-Connemara-Abadia-ylemore-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Las monjas, restauraron todos los espacios de Kylemore: el castillo, ya muy retocado por los duques, la iglesia g\u00f3tica y el jard\u00edn que volvi\u00f3 a tener el esplendor del pasado.<\/p>\n<h2>La <em>Kylemore Abbey School<\/em>: la famosa escuela de Kylemore<\/h2>\n<p>La comunidad benedictina abri\u00f3, en 1923, un <strong>internado para ni\u00f1as<\/strong> \u2013la <em><strong>Kylemore Abbey School<\/strong><\/em>\u2013 que pronto atraer\u00eda a las <strong>hijas de la nobleza irlandesa<\/strong> y luego a <strong>hijas de famosos y famosas de todo el mundo<\/strong>. Algunas de sus alumnas m\u00e1s conocidas fueron <strong>Anjelica Huston<\/strong> y las princesas de India, hijas del Maraj\u00e1 Ranjit.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21152 size-full\" title=\"Una escultura en el paseo de la abad\u00eda de Kylemore\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Mano.jpg\" alt=\"Irlanda Abadia Kylemore Mano\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Mano.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Mano-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Mano-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>La abad\u00eda de Kylemore hoy<\/h2>\n<p>En 2010 se realizaron los \u00faltimos ex\u00e1menes finales del colegio, que hoy ya est\u00e1 cerrado, aunque en la <strong>abad\u00eda sigue viviendo la comunidad benedictina<\/strong>, en espacios cerrados al turismo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21148 size-full\" title=\"El interior de la abad\u00eda de Kylemore\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Interior-Salon.jpg\" alt=\"Irlanda Abadia Kylemore Interior Salon\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Interior-Salon.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Interior-Salon-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Interior-Salon-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Hoy se pueden visitar los <strong>espacios p\u00fablicos de la abad\u00eda<\/strong>, con los salones donde vivieron los Henry, los duques de Manchester y las monjas \u2013y donde todos dejaron su huella\u2013; la <strong>iglesia g\u00f3tica y el mausoleo de los Henry<\/strong>; y el <strong>impresionante jard\u00edn victoriano amurallado<\/strong>, uno de los pocos a\u00fan en funcionamiento, al que se puede llegar en autob\u00fas o con un bonito paseo de unos 20 minutos. En el jard\u00edn siguen estando los <strong>invernaderos<\/strong> y algunos <strong><em>cottages<\/em><\/strong>, como el del jardinero jefe, restaurados y visitables.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21151 size-full\" title=\"Los jardines de la abad\u00eda de Kylemore\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Jardin.jpg\" alt=\"Irlanda Abadia Kylemore Jardin\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Jardin.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Jardin-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Jardin-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21150 size-full\" title=\"El interior de uno de los cottage-museo en los jardines de la abad\u00eda de Kylemore\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Jardin-Cottage.jpg\" alt=\"Irlanda Abadia Kylemore Jardin Cottage\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Jardin-Cottage.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Jardin-Cottage-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Jardin-Cottage-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Al lado del jard\u00edn hay una <strong>casa de t\u00e9<\/strong>, donde probar los deliciosos <em>scones,<\/em> los bollos anglosajones que se suelen tomar con el t\u00e9, y otros productos fabricados por las monjas; en el castillo se puede ver un <strong>audiovisual<\/strong> o dar un <strong>paseo guiado con una gu\u00eda<\/strong> que os contar\u00e1 su historia; y en el parque se pueden hasta hacer<strong> rutas de 1 a 3 horas de duraci\u00f3n por las monta\u00f1as de Kylemore<\/strong>, llegando hasta la estatua del sagrado coraz\u00f3n o m\u00e1s all\u00e1 y disfrutando las <strong>vistas al valle de Kylemore y a los lagos de Connemara<\/strong> \u2013los paseos son guiados y hay que reservarlos\u2013. Ah, y cerca del mausoleo est\u00e1 la \u201c<strong>piedra de planchar<\/strong>\u201d, rodeada de <strong>leyendas<\/strong> y que concede deseos a qui\u00e9n consigue lanzar una piedra a su parte superior, d\u00e1ndole la espalda\u2026<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21154 size-full\" title=\"La piedra de planchar... \u00bfconseguir\u00e1s que se cumplan tus deseos?\" src=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Piedra-de-Planchar.jpg\" alt=\"Irlanda Abadia Kylemore Piedra de Planchar\" width=\"640\" height=\"427\" srcset=\"https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Piedra-de-Planchar.jpg 640w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Piedra-de-Planchar-300x200.jpg 300w, https:\/\/saltaconmigo.com\/blog\/wp-content\/uploads\/2015\/11\/Irlanda-Abadia-Kylemore-Piedra-de-Planchar-360x240.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><em>En un sitio con tantas historias, \u00a1es imposible aburrirse!<\/em><\/p>\n<p>M\u00e1s informaci\u00f3n, con los <strong>precios y horarios de la abad\u00eda<\/strong>, en la <strong><a href=\"http:\/\/www.kylemoreabbeytourism.ie\/\" target=\"_blank\" rel=\"noopener noreferrer\">p\u00e1gina oficial de la Kylemore Abbey<\/a><\/strong>.<\/p>\n<div class=\"cajaVenta\">\n<p>\u00bfTe quieres de ir de <strong>viaje a Irlanda por libre<\/strong>? Aqu\u00ed puedes hacerlo:<\/p>\n<ul class=\"avion\">\n<li>Busca tu <strong>vuelo a Dubl\u00edn<\/strong> <a title=\"Vuelos baratos a Irlanda\" href=\"https:\/\/www.skyscanner.net\/g\/referrals\/v1\/flights\/cheap-flights-to?adId=1100662&amp;campaignId=13416&amp;currency=EUR&amp;destination=DUB&amp;locale=es-ES&amp;market=ES&amp;mediaPartnerId=1205554\" target=\"_blank\" rel=\"sponsored nofollow noopener noreferrer\">aqu\u00ed<\/a>.<\/li>\n<\/ul>\n<ul class=\"hotel\">\n<li>Escoge el <strong>hotel que m\u00e1s te guste al mejor precio<\/strong> en <a title=\"Reserva tu hotel al mejor precio\" href=\"http:\/\/www.booking.com\/searchresults.html?region=2659&amp;aid=844890\" target=\"_blank\" rel=\"sponsored nofollow noopener noreferrer\">Connemara<\/a>.<\/li>\n<\/ul>\n<ul class=\"coche\">\n<li><strong>Alquila el coche<\/strong> en Irlanda al mejor precio comparando entre varias compa\u00f1\u00edas <a title=\"Alquila tu coche al mejor precio\" href=\"https:\/\/www.booking.com\/cars\/index.html?aid=844890\" target=\"_blank\" rel=\"sponsored nofollow noopener noreferrer\">aqu\u00ed<\/a>.<\/li>\n<\/ul>\n<ul class=\"guias\">\n<li>Las <strong>mejores gu\u00edas de Irlanda<\/strong> <a title=\"Compra tu gu\u00eda de viaje al mejor precio\" href=\"http:\/\/amzn.to\/2tDzYqR\" target=\"_blank\" rel=\"sponsored nofollow noopener noreferrer\">aqu\u00ed<\/a>.<\/li>\n<\/ul>\n<ul class=\"tour\">\n<li>Contrata tu <strong><em>tour<\/em> guiado en Irlanda<\/strong> <a href=\"https:\/\/www.civitatis.com\/es\/irlanda\/?aid=1259\" target=\"_blank\" rel=\"sponsored nofollow noopener noreferrer\">aqu\u00ed<\/a>.<\/li>\n<\/ul>\n<ul class=\"seguro\">\n<li>Contrata tu <strong>seguro de viaje con un 5% de descuento<\/strong> <a title=\"Contrata tu seguro de viaje al mejor precio\" href=\"https:\/\/www.iatiseguros.com\/contrato_agencia.phtml?id=447&amp;r=21058501929524\" target=\"_blank\" rel=\"sponsored nofollow noopener noreferrer\">aqu\u00ed<\/a>.<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La \u201cbelleza salvaje\u201d de Connemara ya nos hab\u00eda conquistado cuando llegamos a Kylemore esperando encontrarnos con una abad\u00eda. Connemara segu\u00eda sorprendi\u00e9ndonos. S\u00ed, sus carreteras sinuosas segu\u00edan llev\u00e1ndonos a lo inesperado. Porque la Kylemore Abbey no es s\u00f3lo una abad\u00eda, ni un castillo, ni un parque, ni una iglesia, ni un [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":21145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,360],"tags":[345],"class_list":["post-21141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-irlanda","tag-345"],"_links":{"self":[{"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/posts\/21141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/comments?post=21141"}],"version-history":[{"count":1,"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/posts\/21141\/revisions"}],"predecessor-version":[{"id":54663,"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/posts\/21141\/revisions\/54663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/media\/21145"}],"wp:attachment":[{"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/media?parent=21141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/categories?post=21141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saltaconmigo.com\/blog\/wp-json\/wp\/v2\/tags?post=21141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}